{"id":125,"date":"2019-07-05T09:57:35","date_gmt":"2019-07-05T07:57:35","guid":{"rendered":"http:\/\/mas.visualmedia7.alfahosting.org\/?page_id=125"},"modified":"2024-10-22T14:06:14","modified_gmt":"2024-10-22T12:06:14","slug":"membranpresse-velvet-geschlossenes-system-2","status":"publish","type":"page","link":"https:\/\/mas-keltereiprodukte.de\/en\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/","title":{"rendered":"Velvet"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#f2f2f2&#8243; custom_padding=&#8220;||34px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1 style=\"text-align: center;\">Membranpresse Velvet \u2013 geschlossenes System <\/h1>\n<p>[\/et_pb_text][et_pb_divider color=&#8220;#ff9000&#8243; divider_weight=&#8220;2px&#8220; _builder_version=&#8220;4.16&#8243; width=&#8220;50%&#8220; module_alignment=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#FFFFFF&#8220; custom_padding=&#8220;47px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Velvet T Serie<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2021\/05\/1NE_8660-Modifica.jpg&#8220; title_text=&#8220;1NE_8660-Modifica&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2019\/07\/velvet-t_26-75333.jpg&#8220; title_text=&#8220;velvet-t_26-75333&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2021\/05\/dm-002693.jpg&#8220; title_text=&#8220;dm-002693&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span data-contrast=\"auto\">Modelle:<\/span>\u00a0 <span data-contrast=\"auto\">Velvet T11.5, <\/span><span data-contrast=\"auto\">Velvet T15, V<\/span><span data-contrast=\"auto\">elvet T26, <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Velvet T32,<\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\"> Velvet T43, <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Velvet T60, <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Velvet T75<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:3540,&quot;335559731&quot;:708,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><strong>Technische Beschreibung:<\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><strong>\u00a0<\/strong><br \/><\/span><span data-contrast=\"auto\">Horizontale pneumatische Membranpresse\u00a0mit geschlossener\u00a0Edelstahltrommel\u00a0AISI 304\u00a0und\u00a0Sicherheitsberstscheibe.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"> \u00a0<\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Zahlreiche polierte innenliegende Kan\u00e4le, einfache Reinigung dank eines Systems f\u00fcr schnelle Demontage<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\">.<\/span><\/p>\n<p><span data-contrast=\"auto\">Automatischer hermetischer Deckel, pneumatisch abgedichtete<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Pressmembran aus lebensmittelechtem Kunststoff, komplett aufblasbar auch ohne Produkt.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Schnelles Klemmsystem, kein Durchl\u00f6chern der Membran n\u00f6tig.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Maschine versehen mit automatischer\u00a0Zentralbef\u00fcllung\u00a0mit Druckw\u00e4chter und\u00a0Sicherheitsberstscheibe.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Gestell aus lackiertem Stahl mit Mostsammelwanne und Schaltkasten aus Edelstahl, entsprechend den aktuellen europ\u00e4ischen Richtlinien.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">F\u00fcr Modelle VELVET T11.5\/ T15 sind ein Kompressor zum Aufblasen der Membran und ein Hilfskompressor als Option verf\u00fcgbar. Ein <\/span><span data-contrast=\"auto\">Gebl\u00e4se zur schnelleren Absaugung der Membran und ein zweiter Kompressor f\u00fcr die Steuerluft sind integriert. <\/span><span data-contrast=\"auto\">Seitliche Sicherheitsschranke und Not-Halt\u00a0zur\u00a0Sicherheit des Bedieners. Die Maschine entspricht der EG-Richtlinie.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><strong>Handhabung<\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><strong>\u00a0<\/strong><br \/><\/span><span data-contrast=\"auto\">Die Bedienerschnittstelle E-panel \u201eTouch Screen\u201c zeigt einfache und intuitive Graphiken f\u00fcr leichte Handhabung.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span data-contrast=\"auto\">Dies erlaubt die\u00a0Bedienung\u00a0und die Programmierung aller\u00a0Arbeitszyklen der Maschine,\u00a0sowie die \u00dcberwachung des laufenden Prozesses und des Maschinenzustands.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span data-contrast=\"auto\">In dem Bedienfeld sind 30 Pressprogramme, die Funktion \u201eRocking\u201c zum Schwenken der Trommel und das intelligente Programm M.I.P. vorinstalliert.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"> \u00a0<\/span><span data-contrast=\"auto\">Die Bedientafel mit Touch Screen ist auf einem Edelstahlgeh\u00e4use mit verstellbarer Neigung montiert. Au\u00dferdem ist sie zur \u00dcberwinterung, falls gew\u00fcnscht, einfach von der Maschine abnehmbar.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#ffffff&#8220; custom_padding=&#8220;47px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Velvet T 23 &#8211; 34 &#8211; 40 &#8211; 50 &#8211; 65 &#8211; 80<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2021\/05\/2NE_4735-Modifica-copia.jpg&#8220; title_text=&#8220;2NE_4735-Modifica-copia&#8220; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2021\/05\/Velvet-80.jpg&#8220; title_text=&#8220;Velvet-80&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px|||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2021\/05\/Velvet-115.jpg&#8220; title_text=&#8220;Velvet-115&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||0px|||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;8px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span data-contrast=\"auto\">Modelle:<\/span>\u00a0 <span data-contrast=\"auto\">Velvet 23, <\/span><span data-contrast=\"auto\">Velvet 34,<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Velvet 40, <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Velvet 50,<\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\"> Velvet 65, <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Velvet 80<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:1416,&quot;335559731&quot;:708,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><strong>Technische Beschreibung:<\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><br \/><\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Horizontale pneumatische Membranpresse\u00a0mit\u00a0geschlossener\u00a0Edelstahltrommel\u00a0AISI 304\u00a0und\u00a0Sicherheitsberstscheibe.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Zahlreiche polierte innenliegende Kan\u00e4le, einfache Reinigung dank eines Systems f\u00fcr schnelle Demontage.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Automatischer hermetischer Deckel, pneumatisch abgedichtete<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Pressmembran aus lebensmittelechtem Kunststoff, komplett aufblasbar &#8211; auch ohne Produkt. <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Schnelles Klemmsystem, kein Durchl\u00f6chern der Membran n\u00f6tig.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Maschine versehen mit automatischer\u00a0Zentralbef\u00fcllung\u00a0mit Druckw\u00e4chter und\u00a0Sicherheitsberstscheibe.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"> G<\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">estell komplett aus Edelstahl AISI 304 mit Mostsammelwanne und Schaltkasten aus Edelstahl, entsprechend den aktuellen europ\u00e4ischen Richtlinien.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Maschine mit integriertem Kompressor zum Aufblasen der Membran und Gebl\u00e4se zu deren schnellerer Absaugung; ein zweiter Kompressor f\u00fcr die Steuerluft ist integriert.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Seitliche Sicherheitsschranke und Not-Halt\u00a0zur\u00a0Sicherheit des Bedieners. Die Maschine entspricht der EG-Richtlinie.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><\/p>\n<p><strong><span data-contrast=\"auto\" style=\"font-size: 14px;\">Handhabung<\/span><\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"><br \/><\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Die Bedienerschnittstelle E-panel \u201eTouch Screen\u201c zeigt einfache und intuitive Graphiken,\u00a0f\u00fcr leichte\u00a0Handhabung.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Dies\u00a0erlaubt\u00a0die\u00a0Bedienung\u00a0und die Programmierung aller\u00a0Arbeitszyklen der Maschine,\u00a0sowie die \u00dcberwachung des laufenden Prozesses und des Maschinenzustands.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">In dem Bedienfeld sind 30 Pressprogramme, die Funktion \u201eRocking\u201c zum Schwenken der Trommel und das intelligente Programm M.I.P. vorinstalliert.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\"> <\/span><span data-contrast=\"auto\" style=\"font-size: 14px;\">Die Bedientafel mit Touch Screen ist auf einem Edelstahlgeh\u00e4use mit verstellbarer Neigung montiert. Au\u00dferdem ist sie zur \u00dcberwinterung, falls gew\u00fcnscht, einfach von der Maschine abnehmbar.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\" style=\"font-size: 14px;\">\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#FFFFFF&#8220; custom_padding=&#8220;47px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>Velvet XZ 15 &#8211; 23 &#8211; 34<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; _builder_version=&#8220;4.16&#8243; min_height=&#8220;93px&#8220; custom_padding=&#8220;2px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2019\/07\/VELVET-XZ-3411.jpg&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2019\/07\/geschlossenes-system11.jpg&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_image src=&#8220;https:\/\/mas-keltereiprodukte.de\/wp-content\/uploads\/2019\/07\/elektrische_-Schalttafel11.jpg&#8220; align_tablet=&#8220;center&#8220; align_phone=&#8220;&#8220; align_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span data-contrast=\"auto\">Modelle:<\/span>\u00a0 <span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\"><\/span><span data-contrast=\"auto\">Velvet XZ 15, <\/span><span data-contrast=\"auto\">Velvet XZ 23,<\/span> <span data-contrast=\"auto\">Velvet XZ 34<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:708,&quot;335559731&quot;:708,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><\/p>\n<p><strong>Technische Beschreibung:<\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\"><br \/><\/span><span data-contrast=\"auto\">Horizontale pneumatische Membranpresse mit geschlossener Edelstahltrommel AISI 304.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Zahlreiche polierte innenliegende Kan\u00e4le, einfache Reinigung dank eines Systems f\u00fcr schnelle Demontage. <\/span><span data-contrast=\"auto\">Gro\u00dfe Doppel-T\u00fcr zur manuellen Bet\u00e4tigung, mit mechanischer Sicherheitsverriegelung.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Pressmembran aus lebensmittelechtem Kunststoff, komplett aufblasbar &#8211; auch ohne Produkt. <\/span><span data-contrast=\"auto\">Schnelles Klemmsystem, kein Durchl\u00f6chern der Membran n\u00f6tig.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Gestell komplett aus Edelstahl AISI 304 mit Mostsammelwanne und Schaltkasten aus Edelstahl, entsprechend den aktuellen europ\u00e4ischen Richtlinien.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Maschine mit integriertem Kompressor zum Aufblasen der Membran und Gebl\u00e4se zu deren schnellerer Absaugung; ein zweiter Kompressor f\u00fcr die Steuerluft ist integriert.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Seitliche Sicherheitsschranke und Not-Halt zur Sicherheit des Bedieners. Die Maschine entspricht der EG-Richtlinie.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><\/p>\n<p><strong>Handhabung<\/strong><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\"><br \/><\/span><span data-contrast=\"auto\">Die Bedienerschnittstelle E-panel \u201eTouch Screen\u201c zeigt einfache und intuitive Graphiken, f\u00fcr leichte Handhabung.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Dies\u00a0erlaubt\u00a0die Bedienung und die Programmierung aller Arbeitszyklen der Maschine, sowie die \u00dcberwachung des laufenden Prozesses und des Maschinenzustands.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">In dem Bedienfeld sind 30 Pressprogramme, die Funktion \u201eRocking\u201c zum Schwenken der Trommel und das intelligente Programm M.I.P. vorinstalliert.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><span data-contrast=\"auto\">Die Bedientafel mit Touch Screen ist auf einem Edelstahlgeh\u00e4use mit verstellbarer Neigung montiert. Au\u00dferdem ist sie zur \u00dcberwinterung, falls gew\u00fcnscht, einfach von der Maschine abnehmbar.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:256}\">\u00a0<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#f7f7f7&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1 style=\"text-align: center;\">Kontaktieren Sie uns<\/h1>\n<p>[\/et_pb_text][et_pb_button button_text=&#8220;Anfrage &#8220; button_alignment=&#8220;center&#8220; _builder_version=&#8220;4.27.2&#8243; custom_button=&#8220;on&#8220; button_text_size=&#8220;18px&#8220; button_text_color=&#8220;#ffffff&#8220; button_bg_color=&#8220;#ff9000&#8243; button_border_width=&#8220;1px&#8220; button_font=&#8220;||||||||&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; button_url=&#8220;https:\/\/mas-keltereiprodukte.de\/kontakt\/&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Membranpresse Velvet \u2013 geschlossenes System Velvet T SerieModelle:\u00a0 Velvet T11.5, Velvet T15, Velvet T26, Velvet T32, Velvet T43, Velvet T60, Velvet T75\u00a0 Technische Beschreibung:\u00a0Horizontale pneumatische Membranpresse\u00a0mit geschlossener\u00a0Edelstahltrommel\u00a0AISI 304\u00a0und\u00a0Sicherheitsberstscheibe. \u00a0Zahlreiche polierte innenliegende Kan\u00e4le, einfache Reinigung dank eines Systems f\u00fcr schnelle Demontage. Automatischer hermetischer Deckel, pneumatisch abgedichtete Pressmembran aus lebensmittelechtem Kunststoff, komplett aufblasbar auch ohne Produkt.\u00a0 Schnelles [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":362,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","footnotes":""},"class_list":["post-125","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Velvet - Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mas-keltereiprodukte.de\/en\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Velvet - Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH\" \/>\n<meta property=\"og:description\" content=\"Membranpresse Velvet \u2013 geschlossenes System Velvet T SerieModelle:\u00a0 Velvet T11.5, Velvet T15, Velvet T26, Velvet T32, Velvet T43, Velvet T60, Velvet T75\u00a0 Technische Beschreibung:\u00a0Horizontale pneumatische Membranpresse\u00a0mit geschlossener\u00a0Edelstahltrommel\u00a0AISI 304\u00a0und\u00a0Sicherheitsberstscheibe. \u00a0Zahlreiche polierte innenliegende Kan\u00e4le, einfache Reinigung dank eines Systems f\u00fcr schnelle Demontage. Automatischer hermetischer Deckel, pneumatisch abgedichtete Pressmembran aus lebensmittelechtem Kunststoff, komplett aufblasbar auch ohne Produkt.\u00a0 Schnelles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mas-keltereiprodukte.de\/en\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T12:06:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/weinpressen\\\/membranpresse-velvet-geschlossenes-system-2\\\/\",\"url\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/weinpressen\\\/membranpresse-velvet-geschlossenes-system-2\\\/\",\"name\":\"Velvet - Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/#website\"},\"datePublished\":\"2019-07-05T07:57:35+00:00\",\"dateModified\":\"2024-10-22T12:06:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/weinpressen\\\/membranpresse-velvet-geschlossenes-system-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mas-keltereiprodukte.de\\\/weinpressen\\\/membranpresse-velvet-geschlossenes-system-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/weinpressen\\\/membranpresse-velvet-geschlossenes-system-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weinpressen\",\"item\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/weinpressen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Velvet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/#website\",\"url\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/\",\"name\":\"Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mas-keltereiprodukte.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Velvet - Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mas-keltereiprodukte.de\/en\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/","og_locale":"en_GB","og_type":"article","og_title":"Velvet - Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH","og_description":"Membranpresse Velvet \u2013 geschlossenes System Velvet T SerieModelle:\u00a0 Velvet T11.5, Velvet T15, Velvet T26, Velvet T32, Velvet T43, Velvet T60, Velvet T75\u00a0 Technische Beschreibung:\u00a0Horizontale pneumatische Membranpresse\u00a0mit geschlossener\u00a0Edelstahltrommel\u00a0AISI 304\u00a0und\u00a0Sicherheitsberstscheibe. \u00a0Zahlreiche polierte innenliegende Kan\u00e4le, einfache Reinigung dank eines Systems f\u00fcr schnelle Demontage. Automatischer hermetischer Deckel, pneumatisch abgedichtete Pressmembran aus lebensmittelechtem Kunststoff, komplett aufblasbar auch ohne Produkt.\u00a0 Schnelles [&hellip;]","og_url":"https:\/\/mas-keltereiprodukte.de\/en\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/","og_site_name":"Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH","article_modified_time":"2024-10-22T12:06:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mas-keltereiprodukte.de\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/","url":"https:\/\/mas-keltereiprodukte.de\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/","name":"Velvet - Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH","isPartOf":{"@id":"https:\/\/mas-keltereiprodukte.de\/#website"},"datePublished":"2019-07-05T07:57:35+00:00","dateModified":"2024-10-22T12:06:14+00:00","breadcrumb":{"@id":"https:\/\/mas-keltereiprodukte.de\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mas-keltereiprodukte.de\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mas-keltereiprodukte.de\/weinpressen\/membranpresse-velvet-geschlossenes-system-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mas-keltereiprodukte.de\/"},{"@type":"ListItem","position":2,"name":"Weinpressen","item":"https:\/\/mas-keltereiprodukte.de\/weinpressen\/"},{"@type":"ListItem","position":3,"name":"Velvet"}]},{"@type":"WebSite","@id":"https:\/\/mas-keltereiprodukte.de\/#website","url":"https:\/\/mas-keltereiprodukte.de\/","name":"Weinpressen und Keltereianlagen - M.A.S. Keltereiprodukte GMBH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mas-keltereiprodukte.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/pages\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/comments?post=125"}],"version-history":[{"count":20,"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/pages\/125\/revisions"}],"predecessor-version":[{"id":2010,"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/pages\/125\/revisions\/2010"}],"up":[{"embeddable":true,"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/pages\/362"}],"wp:attachment":[{"href":"https:\/\/mas-keltereiprodukte.de\/en\/wp-json\/wp\/v2\/media?parent=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}